{"id":70336,"date":"2022-03-03T15:10:35","date_gmt":"2022-03-03T15:10:35","guid":{"rendered":"https:\/\/www.viajamenorca.com\/?p=19785"},"modified":"2026-05-09T22:41:56","modified_gmt":"2026-05-09T22:41:56","slug":"mercato-del-pesce","status":"publish","type":"post","link":"https:\/\/www.viajamenorca.com\/it\/cosa-fare-a-minorca\/fiere-e-mercati\/mercato-del-pesce\/","title":{"rendered":"Mercat del Peix, Mah\u00f3n"},"content":{"rendered":"\n<h3><span style=\"font-size: 14pt;\">Pescheria municipale situata nel centro della citt\u00e0,<\/span><span style=\"font-size: 14pt;\">\u00a0a soli 50 metri dal <a href=\"https:\/\/www.viajamenorca.com\/it\/?p=70293\"><strong>Mercato del Carmen<\/strong><\/a><\/span><span style=\"font-size: 14pt;\">. Dispone di un mercato gastronomico dove potrete degustare i prodotti locali.<\/span><\/h3>\n<figure id=\"attachment_20320\" aria-describedby=\"caption-attachment-20320\" style=\"width: 480px\" class=\"wp-caption alignright\"><a href=\"https:\/\/www.viajamenorca.com\/wp-content\/uploads\/2022\/02\/IMG_20220204_125006_1-scaled.jpg\"><img decoding=\"async\" class=\"wp-image-20320\" title=\"Mercato del Claustre del Carme, Mah\u00f3n\" src=\"https:\/\/www.viajamenorca.com\/wp-content\/uploads\/2022\/02\/IMG_20220204_125006_1-350x161.jpg\" alt=\"fish market Mah\u00f3n\" width=\"490\" height=\"225\" srcset=\"https:\/\/www.viajamenorca.com\/wp-content\/uploads\/2022\/02\/IMG_20220204_125006_1-350x161.jpg 350w, https:\/\/www.viajamenorca.com\/wp-content\/uploads\/2022\/02\/IMG_20220204_125006_1-1024x471.jpg 1024w, https:\/\/www.viajamenorca.com\/wp-content\/uploads\/2022\/02\/IMG_20220204_125006_1-768x353.jpg 768w, https:\/\/www.viajamenorca.com\/wp-content\/uploads\/2022\/02\/IMG_20220204_125006_1-1536x707.jpg 1536w, https:\/\/www.viajamenorca.com\/wp-content\/uploads\/2022\/02\/IMG_20220204_125006_1-2048x942.jpg 2048w\" sizes=\"(max-width: 490px) 100vw, 490px\" \/><\/a><figcaption id=\"caption-attachment-20320\" class=\"wp-caption-text\"><span style=\"font-size: 12pt;\">Mercato del pesce, Mah\u00f3n<\/span><\/figcaption><\/figure>\n<h2><span style=\"font-size: 18pt;\">Storia del mercato<\/span><\/h2>\n<h3><span style=\"font-size: 14pt;\">Anticamente il pesce veniva venduto direttamente nel porto di Mah\u00f3n; successivamente, le attivit\u00e0 si trasferirono nel mercato del Chiostro del Carmen.<\/span><\/h3>\n<figure id=\"attachment_20315\" aria-describedby=\"caption-attachment-20315\" style=\"width: 320px\" class=\"wp-caption alignright\"><a href=\"https:\/\/www.viajamenorca.com\/wp-content\/uploads\/2022\/02\/IMG_20220204_125310_1-scaled.jpg\"><img decoding=\"async\" class=\"wp-image-20315\" title=\"Mercato del pesce, Mah\u00f3n\" src=\"https:\/\/www.viajamenorca.com\/wp-content\/uploads\/2022\/02\/IMG_20220204_125310_1-350x161.jpg\" alt=\"Pescheria a Mah\u00f3n, Minorca\" width=\"330\" height=\"152\" srcset=\"https:\/\/www.viajamenorca.com\/wp-content\/uploads\/2022\/02\/IMG_20220204_125310_1-350x161.jpg 350w, https:\/\/www.viajamenorca.com\/wp-content\/uploads\/2022\/02\/IMG_20220204_125310_1-1024x472.jpg 1024w, https:\/\/www.viajamenorca.com\/wp-content\/uploads\/2022\/02\/IMG_20220204_125310_1-768x354.jpg 768w, https:\/\/www.viajamenorca.com\/wp-content\/uploads\/2022\/02\/IMG_20220204_125310_1-1536x709.jpg 1536w, https:\/\/www.viajamenorca.com\/wp-content\/uploads\/2022\/02\/IMG_20220204_125310_1-2048x945.jpg 2048w\" sizes=\"(max-width: 330px) 100vw, 330px\" \/><\/a><figcaption id=\"caption-attachment-20315\" class=\"wp-caption-text\"><span style=\"font-size: 12pt;\">Mercat del Peix Mah\u00f3n<\/span><\/figcaption><\/figure>\n<p>Solo nel 1927 fu costruita la nuova pescheria municipale, opera dell&#8217;architetto <a href=\"https:\/\/es.wikipedia.org\/wiki\/Francesc_Femen%C3%ADas_i_F%C3%A1bregues\" target=\"_blank\" rel=\"noopener\" data-wplink-edit=\"true\"><strong>Francesc Femen\u00edas<\/strong><\/a> durante il regno di Alfonso XIII, che inaugur\u00f2 personalmente il mercato il 12 novembre 1927.<\/p>\n<p>Il mercato \u00e8 composto da due parti: una dove si trovano le tradizionali pescherie e un&#8217;altra con un mercato gastronomico dove potrete assaggiare i prodotti del mercato stesso.<\/p>\n<h2><span style=\"font-size: 18pt;\">Un mercato molto frequentato<\/span><\/h2>\n<p>Attualmente il &#8220;Mercat del Peix&#8221; gode di grande vitalit\u00e0 ed \u00e8 un luogo molto frequentato, grazie in parte all&#8217;integrazione del mercato gastronomico all&#8217;interno dello stesso spazio. Durante tutto l&#8217;anno vengono organizzati numerosi eventi gastronomici, culturali e musicali, il che lo rende un luogo ideale per l&#8217;aperitivo e per gustare tapas, attivit\u00e0 molto popolari tra gli abitanti di Minorca.<\/p>\n<h2><span style=\"font-size: 18pt;\">Informazioni utili<\/span><\/h2>\n<ul>\n<li><span style=\"font-size: 12pt;\">Potete approfittarne per visitare il <a href=\"https:\/\/www.viajamenorca.com\/it\/?p=70293\"><strong>Mercato del Chiostro del Carmen<\/strong><\/a> situato a soli 50 metri.<\/span><\/li>\n<li><span style=\"font-size: 12pt;\">Dietro il mercato del Carmen c&#8217;\u00e8 un pratico ascensore che collega al porto di Mah\u00f3n, dal quale si possono ammirare viste spettacolari. Non dimenticate la vostra fotocamera!<\/span><\/li>\n<li><span style=\"font-size: 12pt;\">Nelle vicinanze si trova un ampio parcheggio a zona blu, lungo la Costa de ses Voltes.<\/span><\/li>\n<\/ul>\n<h2><span style=\"font-size: 18pt;\">Come arrivare\u00a0<\/span><\/h2>\n<p><span style=\"font-size: 12pt;\"><strong>INDIRIZZO:<\/strong> Mercat des Peix, Plaza de Espa\u00f1a n.1, <strong><a href=\"https:\/\/www.viajamenorca.com\/it\/guida-turistica\/popolazioni\/mao-mahon\/\">Mah\u00f3n<\/a><\/strong> <div class=\"g g-9\"><div class=\"g-single a-51\"><a href=\"https:\/\/www.civitatis.com\/it\/fornells\/giro-barca-cale-nord\/?aid=99960\" target=\"_blank\" rel=\"nofollow\">\r\n    <img decoding=\"async\" src=\"https:\/\/www.viajamenorca.com\/wp-content\/uploads\/2026\/02\/ITALIANO_ROSE-5-1.jpg\" width=\"350\" height=\"210\" title=\"Gita in barca alle calette del nord\" alt=\"Gita in barca alle calette del nord\" \/>\r\n<\/a><\/div><\/div><\/span><\/p>\n<h3><strong><a href=\"https:\/\/g.page\/mercatfemenias?share\" target=\"_blank\" rel=\"noopener\"><span style=\"font-size: 14pt;\">Apri la mappa con indicazioni GPS<\/span><\/a><\/strong><\/h3>\n<h2><span style=\"font-size: 18pt;\">Informazioni e orari<\/span><\/h2>\n<p>(Orario invernale)<\/p>\n<p><span style=\"font-size: 12pt;\"><b>Pescheria<\/b><strong style=\"font-size: 12pt;\">:<\/strong><span style=\"font-size: 12pt;\"> da marted\u00ec a sabato dalle 7:00 alle 14:00.<\/span><\/span><\/p>\n<p><strong>Mercato Gastronomico:<\/strong> venerd\u00ec, sabato e domenica dalle 11:00 alle 16:00 e dalle 19:00 alle 23:00.<\/p>\n<h2><span style=\"font-size: 18pt;\">Cosa fare a Mah\u00f3n<\/span><\/h2>\n<h2><span style=\"font-size: 14pt;\">Attivit\u00e0 di svago &#8211; Visite guidate<\/span><\/h2>\n<div style=\"text-align: center;\"><script>function loadScript(url, callback){var script=document.createElement('script'); script.type='text\/javascript'; if (script.readyState){script.onreadystatechange=function(){if (script.readyState=='loaded' || script.readyState=='complete'){script.onreadystatechange=null; callback();}};}else{script.onload=function(){callback();};}script.src=url; document.getElementsByTagName('head')[0].appendChild(script);}loadScript('https:\/\/cdn2.civitatis.com\/js\/vendor\/iframeResizer.min.js', function(){iFrameResize({checkOrigin:false,initCallback:function(iframe){setTimeout(function(){var resizeEvent = window.document.createEvent('UIEvents'); resizeEvent.initUIEvent('resize', true, false, window, 0); iframe.dispatchEvent(resizeEvent);});}})})<\/script><iframe class=\"civitatis-iframe\" style=\"max-width: 100%;\" src=\"https:\/\/www.civitatis.com\/widget-activities\/?affiliated=99960&amp;display=cosy&amp;cant=6&amp;lang=it&amp;currency=EUR&amp;destination=4123&amp;activities=90458,128834,2750,20698,2335&amp;transfer=1&amp;cmp=Widget_Mahon_ES&amp;width=100%&amp;hideButton=0&amp;centerContent=1&amp;typeSelection=manual&amp;color=1d5a8f&amp;typography=Montserrat&amp;removeBackground=1&amp;showShadow=1&amp;roundedButtons=1\" width=\"100%\" frameborder=\"0\" data-maxwidth=\"100%\"><\/iframe><\/div>\n<h2 style=\"text-align: center;\"><span style=\"font-size: 18pt;\">Galleria fotografica<\/span><\/h2>\n\n\n\n<figure class=\"wp-block-gallery has-nested-images columns-6 is-cropped wp-block-gallery-1 is-layout-flex wp-block-gallery-is-layout-flex\">\n<figure class=\"wp-block-image size-thumbnail\"><a href=\"https:\/\/www.viajamenorca.com\/wp-content\/uploads\/2022\/02\/IMG_20220204_125104-150x150.jpg\"><img decoding=\"async\" width=\"150\" height=\"150\" data-id=\"20323\" src=\"https:\/\/www.viajamenorca.com\/wp-content\/uploads\/2022\/02\/IMG_20220204_125104-150x150.jpg\" alt=\"\" class=\"wp-image-20323\"\/><\/a><\/figure>\n\n\n\n<figure class=\"wp-block-image size-thumbnail\"><a href=\"https:\/\/www.viajamenorca.com\/wp-content\/uploads\/2022\/02\/IMG_20220204_124939_1_stitch-scaled.jpg\"><img decoding=\"async\" width=\"150\" height=\"150\" data-id=\"20318\" src=\"https:\/\/www.viajamenorca.com\/wp-content\/uploads\/2022\/02\/IMG_20220204_124939_1_stitch-150x150.jpg\" alt=\"Mercato del pesce\" class=\"wp-image-20318\" title=\"Mercato del pesce di Mah\u00f3n, Minorca\"\/><\/a><\/figure>\n\n\n\n<figure class=\"wp-block-image size-thumbnail\"><a href=\"https:\/\/www.viajamenorca.com\/wp-content\/uploads\/2022\/02\/IMG_20220204_124952-scaled.jpg\"><img decoding=\"async\" width=\"150\" height=\"150\" data-id=\"20319\" src=\"https:\/\/www.viajamenorca.com\/wp-content\/uploads\/2022\/02\/IMG_20220204_124952-150x150.jpg\" alt=\"\" class=\"wp-image-20319\"\/><\/a><\/figure>\n\n\n\n<figure class=\"wp-block-image size-thumbnail\"><a href=\"https:\/\/www.viajamenorca.com\/wp-content\/uploads\/2022\/02\/IMG_20220204_125006_1-scaled.jpg\"><img decoding=\"async\" width=\"150\" height=\"150\" data-id=\"20320\" src=\"https:\/\/www.viajamenorca.com\/wp-content\/uploads\/2022\/02\/IMG_20220204_125006_1-150x150.jpg\" alt=\"Mercato del pesce di Mah\u00f3n, Minorca\" class=\"wp-image-20320\" title=\"Mercato del pesce di Mah\u00f3n\"\/><\/a><\/figure>\n\n\n\n<figure class=\"wp-block-image size-thumbnail\"><a href=\"https:\/\/www.viajamenorca.com\/wp-content\/uploads\/2022\/02\/IMG_20220204_125117_1-scaled.jpg\"><img decoding=\"async\" width=\"150\" height=\"150\" data-id=\"20324\" src=\"https:\/\/www.viajamenorca.com\/wp-content\/uploads\/2022\/02\/IMG_20220204_125117_1-150x150.jpg\" alt=\"\" class=\"wp-image-20324\"\/><\/a><\/figure>\n\n\n\n<figure class=\"wp-block-image size-thumbnail\"><a href=\"https:\/\/www.viajamenorca.com\/wp-content\/uploads\/2022\/02\/IMG_20220204_125039-150x150.jpg\"><img decoding=\"async\" width=\"150\" height=\"150\" data-id=\"20321\" src=\"https:\/\/www.viajamenorca.com\/wp-content\/uploads\/2022\/02\/IMG_20220204_125039-150x150.jpg\" alt=\"\" class=\"wp-image-20321\"\/><\/a><\/figure>\n\n\n\n<figure class=\"wp-block-image size-thumbnail\"><a href=\"https:\/\/www.viajamenorca.com\/wp-content\/uploads\/2022\/02\/IMG_20220204_125051-scaled.jpg\"><img decoding=\"async\" width=\"150\" height=\"150\" data-id=\"20322\" src=\"https:\/\/www.viajamenorca.com\/wp-content\/uploads\/2022\/02\/IMG_20220204_125051-150x150.jpg\" alt=\"\" class=\"wp-image-20322\"\/><\/a><\/figure>\n\n\n\n<figure class=\"wp-block-image size-thumbnail\"><a href=\"https:\/\/www.viajamenorca.com\/wp-content\/uploads\/2022\/02\/IMG_20220204_125153_1-scaled.jpg\"><img decoding=\"async\" width=\"150\" height=\"150\" data-id=\"20326\" src=\"https:\/\/www.viajamenorca.com\/wp-content\/uploads\/2022\/02\/IMG_20220204_125153_1-150x150.jpg\" alt=\"\" class=\"wp-image-20326\"\/><\/a><\/figure>\n\n\n\n<figure class=\"wp-block-image size-thumbnail\"><a href=\"https:\/\/www.viajamenorca.com\/wp-content\/uploads\/2022\/02\/IMG_20220204_125200-scaled.jpg\"><img decoding=\"async\" width=\"150\" height=\"150\" data-id=\"20310\" src=\"https:\/\/www.viajamenorca.com\/wp-content\/uploads\/2022\/02\/IMG_20220204_125200-150x150.jpg\" alt=\"Orari del mercato del pesce, Mah\u00f3n\" class=\"wp-image-20310\" title=\"Orari del mercato del pesce, Mah\u00f3n\"\/><\/a><\/figure>\n\n\n\n<figure class=\"wp-block-image size-thumbnail\"><a href=\"https:\/\/www.viajamenorca.com\/wp-content\/uploads\/2022\/02\/IMG_20220204_125208-scaled.jpg\"><img decoding=\"async\" width=\"150\" height=\"150\" data-id=\"20311\" src=\"https:\/\/www.viajamenorca.com\/wp-content\/uploads\/2022\/02\/IMG_20220204_125208-150x150.jpg\" alt=\"\" class=\"wp-image-20311\"\/><\/a><\/figure>\n\n\n\n<figure class=\"wp-block-image size-thumbnail\"><a href=\"https:\/\/www.viajamenorca.com\/wp-content\/uploads\/2022\/02\/IMG_20220204_125131-scaled.jpg\"><img decoding=\"async\" width=\"150\" height=\"150\" data-id=\"20325\" src=\"https:\/\/www.viajamenorca.com\/wp-content\/uploads\/2022\/02\/IMG_20220204_125131-150x150.jpg\" alt=\"\" class=\"wp-image-20325\"\/><\/a><\/figure>\n\n\n\n<figure class=\"wp-block-image size-thumbnail\"><a href=\"https:\/\/www.viajamenorca.com\/wp-content\/uploads\/2022\/02\/IMG_20220204_125218-scaled.jpg\"><img decoding=\"async\" width=\"150\" height=\"150\" data-id=\"20312\" src=\"https:\/\/www.viajamenorca.com\/wp-content\/uploads\/2022\/02\/IMG_20220204_125218-150x150.jpg\" alt=\"\" class=\"wp-image-20312\"\/><\/a><\/figure>\n\n\n\n<figure class=\"wp-block-image size-thumbnail\"><a href=\"https:\/\/www.viajamenorca.com\/wp-content\/uploads\/2022\/02\/IMG_20220204_125233-150x150.jpg\"><img decoding=\"async\" width=\"150\" height=\"150\" data-id=\"20313\" src=\"https:\/\/www.viajamenorca.com\/wp-content\/uploads\/2022\/02\/IMG_20220204_125233-150x150.jpg\" alt=\"Mercato gastronomico\" class=\"wp-image-20313\" title=\"Mercato gastronomico\"\/><\/a><\/figure>\n\n\n\n<figure class=\"wp-block-image size-thumbnail\"><a href=\"https:\/\/www.viajamenorca.com\/wp-content\/uploads\/2022\/02\/IMG_20220204_125251_1-scaled.jpg\"><img decoding=\"async\" width=\"150\" height=\"150\" data-id=\"20314\" src=\"https:\/\/www.viajamenorca.com\/wp-content\/uploads\/2022\/02\/IMG_20220204_125251_1-150x150.jpg\" alt=\"\" class=\"wp-image-20314\"\/><\/a><\/figure>\n\n\n\n<figure class=\"wp-block-image size-thumbnail\"><a href=\"https:\/\/www.viajamenorca.com\/wp-content\/uploads\/2022\/02\/IMG_20220204_125310_1-scaled.jpg\"><img decoding=\"async\" width=\"150\" height=\"150\" data-id=\"20315\" src=\"https:\/\/www.viajamenorca.com\/wp-content\/uploads\/2022\/02\/IMG_20220204_125310_1-150x150.jpg\" alt=\"Mercato del pesce di Mah\u00f3n, Minorca\" class=\"wp-image-20315\" title=\"Mercato del pesce\"\/><\/a><\/figure>\n\n\n\n<figure class=\"wp-block-image size-thumbnail\"><a href=\"https:\/\/www.viajamenorca.com\/wp-content\/uploads\/2022\/02\/IMG_20220204_125321-scaled.jpg\"><img decoding=\"async\" width=\"150\" height=\"150\" data-id=\"20316\" src=\"https:\/\/www.viajamenorca.com\/wp-content\/uploads\/2022\/02\/IMG_20220204_125321-150x150.jpg\" alt=\"\" class=\"wp-image-20316\"\/><\/a><\/figure>\n\n\n\n<figure class=\"wp-block-image size-thumbnail\"><a href=\"https:\/\/www.viajamenorca.com\/wp-content\/uploads\/2022\/02\/IMG_20220204_125349_1-scaled.jpg\"><img decoding=\"async\" width=\"150\" height=\"150\" data-id=\"20317\" src=\"https:\/\/www.viajamenorca.com\/wp-content\/uploads\/2022\/02\/IMG_20220204_125349_1-150x150.jpg\" alt=\"\" class=\"wp-image-20317\"\/><\/a><\/figure>\n\n\n\n<figure class=\"wp-block-image size-thumbnail\"><a href=\"https:\/\/www.viajamenorca.com\/wp-content\/uploads\/2022\/02\/IMG_20220204_124750-scaled.jpg\"><img decoding=\"async\" width=\"2560\" height=\"1181\" data-id=\"20307\" src=\"https:\/\/www.viajamenorca.com\/wp-content\/uploads\/2022\/02\/IMG_20220204_124750-scaled.jpg\" alt=\"Ascensore del porto di Mah\u00f3n\" class=\"wp-image-20307\" srcset=\"https:\/\/www.viajamenorca.com\/wp-content\/uploads\/2022\/02\/IMG_20220204_124750-scaled.jpg 2560w, https:\/\/www.viajamenorca.com\/wp-content\/uploads\/2022\/02\/IMG_20220204_124750-350x161.jpg 350w, https:\/\/www.viajamenorca.com\/wp-content\/uploads\/2022\/02\/IMG_20220204_124750-1024x472.jpg 1024w, https:\/\/www.viajamenorca.com\/wp-content\/uploads\/2022\/02\/IMG_20220204_124750-768x354.jpg 768w, https:\/\/www.viajamenorca.com\/wp-content\/uploads\/2022\/02\/IMG_20220204_124750-1536x709.jpg 1536w, https:\/\/www.viajamenorca.com\/wp-content\/uploads\/2022\/02\/IMG_20220204_124750-2048x945.jpg 2048w\" sizes=\"(max-width: 2560px) 100vw, 2560px\" \/><\/a><\/figure>\n<\/figure>\n","protected":false},"excerpt":{"rendered":"<p>Pescheria municipale situata nel centro della citt\u00e0,\u00a0a soli 50 metri dal Mercato del Carmen. Dispone di un mercato gastronomico dove potrete degustare i prodotti locali. Storia del mercato Anticamente il &#8230; <\/p>\n<p class=\"read-more-container\"><a title=\"Mercat del Peix, Mah\u00f3n\" class=\"read-more button\" href=\"https:\/\/www.viajamenorca.com\/it\/cosa-fare-a-minorca\/fiere-e-mercati\/mercato-del-pesce\/#more-70336\" aria-label=\"Per saperne di pi\u00f9 su Mercat del Peix, Mah\u00f3n\">Leggi tutto<\/a><\/p>\n","protected":false},"author":1,"featured_media":20318,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[418,1554],"tags":[3819,1546,3820,3818,3817,3821],"class_list":["post-70336","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-ferias-y-mercados","category-fiere-e-mercati","tag-cucina-di-mercato","tag-mahon","tag-mercat-del-peix","tag-mercato-del-pesce","tag-mercato-gastronomico","tag-pescivendolo","resize-featured-image"],"acf":{"elige_un_tipo_de_actividad":"","buscar_por_zonas":""},"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Mercato del pesce di Mah\u00f3n: tapas, pesce fresco, dove mangiare<\/title>\n<meta name=\"description\" content=\"Il mercato del pesce di Mah\u00f3n si trova nel centro della citt\u00e0, molto vicino al mercato di Claustre del Carme, e ospita anche un mercato\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.viajamenorca.com\/it\/cosa-fare-a-minorca\/fiere-e-mercati\/mercato-del-pesce\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Mercato del pesce di Mah\u00f3n: tapas, pesce fresco, dove mangiare\" \/>\n<meta property=\"og:description\" content=\"Il mercato del pesce di Mah\u00f3n si trova nel centro della citt\u00e0, molto vicino al mercato di Claustre del Carme, e ospita anche un mercato\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.viajamenorca.com\/it\/cosa-fare-a-minorca\/fiere-e-mercati\/mercato-del-pesce\/\" \/>\n<meta property=\"og:site_name\" content=\"Viaja a Menorca\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/ViajaMenorca\/\" \/>\n<meta property=\"article:author\" content=\"https:\/\/www.facebook.com\/ViajaMenorca\/\" \/>\n<meta property=\"article:published_time\" content=\"2022-03-03T15:10:35+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2026-05-09T22:41:56+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.viajamenorca.com\/wp-content\/uploads\/2022\/02\/IMG_20220204_124939_1_stitch-scaled.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"2560\" \/>\n\t<meta property=\"og:image:height\" content=\"1124\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"RVM\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@ViajaMenorca\" \/>\n<meta name=\"twitter:site\" content=\"@ViajaMenorca\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"RVM\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"6 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.viajamenorca.com\\\/it\\\/cosa-fare-a-minorca\\\/fiere-e-mercati\\\/mercato-del-pesce\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.viajamenorca.com\\\/it\\\/cosa-fare-a-minorca\\\/fiere-e-mercati\\\/mercato-del-pesce\\\/\"},\"author\":{\"name\":\"RVM\",\"@id\":\"https:\\\/\\\/www.viajamenorca.com\\\/it\\\/#\\\/schema\\\/person\\\/a4a17bcf26fbf36b9726dc16edd0a3fc\"},\"headline\":\"Mercat del Peix, Mah\u00f3n\",\"datePublished\":\"2022-03-03T15:10:35+00:00\",\"dateModified\":\"2026-05-09T22:41:56+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.viajamenorca.com\\\/it\\\/cosa-fare-a-minorca\\\/fiere-e-mercati\\\/mercato-del-pesce\\\/\"},\"wordCount\":316,\"publisher\":{\"@id\":\"https:\\\/\\\/www.viajamenorca.com\\\/it\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.viajamenorca.com\\\/it\\\/cosa-fare-a-minorca\\\/fiere-e-mercati\\\/mercato-del-pesce\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.viajamenorca.com\\\/wp-content\\\/uploads\\\/2022\\\/02\\\/IMG_20220204_124939_1_stitch-scaled.jpg\",\"keywords\":[\"Cucina di mercato\",\"Mahon\",\"Mercat del peix\",\"Mercato del pesce\",\"Mercato gastronomico\",\"Pescivendolo\"],\"articleSection\":[\"Ferias y Mercados\",\"Fiere e mercati\"],\"inLanguage\":\"it-IT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.viajamenorca.com\\\/it\\\/cosa-fare-a-minorca\\\/fiere-e-mercati\\\/mercato-del-pesce\\\/\",\"url\":\"https:\\\/\\\/www.viajamenorca.com\\\/it\\\/cosa-fare-a-minorca\\\/fiere-e-mercati\\\/mercato-del-pesce\\\/\",\"name\":\"Mercato del pesce di Mah\u00f3n: tapas, pesce fresco, dove mangiare\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.viajamenorca.com\\\/it\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.viajamenorca.com\\\/it\\\/cosa-fare-a-minorca\\\/fiere-e-mercati\\\/mercato-del-pesce\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.viajamenorca.com\\\/it\\\/cosa-fare-a-minorca\\\/fiere-e-mercati\\\/mercato-del-pesce\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.viajamenorca.com\\\/wp-content\\\/uploads\\\/2022\\\/02\\\/IMG_20220204_124939_1_stitch-scaled.jpg\",\"datePublished\":\"2022-03-03T15:10:35+00:00\",\"dateModified\":\"2026-05-09T22:41:56+00:00\",\"description\":\"Il mercato del pesce di Mah\u00f3n si trova nel centro della citt\u00e0, molto vicino al mercato di Claustre del Carme, e ospita anche un mercato\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.viajamenorca.com\\\/it\\\/cosa-fare-a-minorca\\\/fiere-e-mercati\\\/mercato-del-pesce\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.viajamenorca.com\\\/it\\\/cosa-fare-a-minorca\\\/fiere-e-mercati\\\/mercato-del-pesce\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.viajamenorca.com\\\/it\\\/cosa-fare-a-minorca\\\/fiere-e-mercati\\\/mercato-del-pesce\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.viajamenorca.com\\\/wp-content\\\/uploads\\\/2022\\\/02\\\/IMG_20220204_124939_1_stitch-scaled.jpg\",\"contentUrl\":\"https:\\\/\\\/www.viajamenorca.com\\\/wp-content\\\/uploads\\\/2022\\\/02\\\/IMG_20220204_124939_1_stitch-scaled.jpg\",\"width\":2560,\"height\":1124,\"caption\":\"fish market Mah\u00f3n\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.viajamenorca.com\\\/it\\\/cosa-fare-a-minorca\\\/fiere-e-mercati\\\/mercato-del-pesce\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Cosa fare a Minorca\",\"item\":\"https:\\\/\\\/www.viajamenorca.com\\\/it\\\/.\\\/cosa-fare-a-minorca\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Fiere e mercati\",\"item\":\"https:\\\/\\\/www.viajamenorca.com\\\/it\\\/.\\\/cosa-fare-a-minorca\\\/fiere-e-mercati\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Mercato del pesce\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.viajamenorca.com\\\/it\\\/#website\",\"url\":\"https:\\\/\\\/www.viajamenorca.com\\\/it\\\/\",\"name\":\"Viaja a Menorca\",\"description\":\"La tua avventura a Minorca inizia qui!\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.viajamenorca.com\\\/it\\\/#organization\"},\"alternateName\":\"Gu\u00eda tur\u00edstica de Menorca\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.viajamenorca.com\\\/it\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.viajamenorca.com\\\/it\\\/#organization\",\"name\":\"Viaja a Menorca - Gu\u00eda tur\u00edstica\",\"alternateName\":\"Viaja a Menorca\",\"url\":\"https:\\\/\\\/www.viajamenorca.com\\\/it\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.viajamenorca.com\\\/it\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.viajamenorca.com\\\/wp-content\\\/uploads\\\/2021\\\/11\\\/viajamenorca.jpg\",\"contentUrl\":\"https:\\\/\\\/www.viajamenorca.com\\\/wp-content\\\/uploads\\\/2021\\\/11\\\/viajamenorca.jpg\",\"width\":714,\"height\":714,\"caption\":\"Viaja a Menorca - Gu\u00eda tur\u00edstica\"},\"image\":{\"@id\":\"https:\\\/\\\/www.viajamenorca.com\\\/it\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/ViajaMenorca\\\/\",\"https:\\\/\\\/x.com\\\/ViajaMenorca\",\"https:\\\/\\\/www.instagram.com\\\/viaja_menorca\\\/?hl=es\",\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UCWtpR3jxp79HeZ8zZfHLhXw\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.viajamenorca.com\\\/it\\\/#\\\/schema\\\/person\\\/a4a17bcf26fbf36b9726dc16edd0a3fc\",\"name\":\"RVM\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.viajamenorca.com\\\/wp-content\\\/litespeed\\\/avatar\\\/f92762d1538920c5ee7c40d8d2c84bc0.jpg?ver=1778553373\",\"url\":\"https:\\\/\\\/www.viajamenorca.com\\\/wp-content\\\/litespeed\\\/avatar\\\/f92762d1538920c5ee7c40d8d2c84bc0.jpg?ver=1778553373\",\"contentUrl\":\"https:\\\/\\\/www.viajamenorca.com\\\/wp-content\\\/litespeed\\\/avatar\\\/f92762d1538920c5ee7c40d8d2c84bc0.jpg?ver=1778553373\",\"caption\":\"RVM\"},\"description\":\"Guia turistica de Menorca creada por un menorquin amante de su tierra, espero que os guste.\",\"sameAs\":[\"http:\\\/\\\/www.viajamenorca.com\",\"https:\\\/\\\/www.facebook.com\\\/ViajaMenorca\\\/\",\"https:\\\/\\\/www.instagram.com\\\/viaja_menorca\\\/?hl=es\",\"https:\\\/\\\/x.com\\\/ViajaMenorca\",\"https:\\\/\\\/www.youtube.com\\\/c\\\/ViajamenorcaEs\",\"https:\\\/\\\/es.wikipedia.org\\\/wiki\\\/Menorca\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Mercato del pesce di Mah\u00f3n: tapas, pesce fresco, dove mangiare","description":"Il mercato del pesce di Mah\u00f3n si trova nel centro della citt\u00e0, molto vicino al mercato di Claustre del Carme, e ospita anche un mercato","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.viajamenorca.com\/it\/cosa-fare-a-minorca\/fiere-e-mercati\/mercato-del-pesce\/","og_locale":"it_IT","og_type":"article","og_title":"Mercato del pesce di Mah\u00f3n: tapas, pesce fresco, dove mangiare","og_description":"Il mercato del pesce di Mah\u00f3n si trova nel centro della citt\u00e0, molto vicino al mercato di Claustre del Carme, e ospita anche un mercato","og_url":"https:\/\/www.viajamenorca.com\/it\/cosa-fare-a-minorca\/fiere-e-mercati\/mercato-del-pesce\/","og_site_name":"Viaja a Menorca","article_publisher":"https:\/\/www.facebook.com\/ViajaMenorca\/","article_author":"https:\/\/www.facebook.com\/ViajaMenorca\/","article_published_time":"2022-03-03T15:10:35+00:00","article_modified_time":"2026-05-09T22:41:56+00:00","og_image":[{"width":2560,"height":1124,"url":"https:\/\/www.viajamenorca.com\/wp-content\/uploads\/2022\/02\/IMG_20220204_124939_1_stitch-scaled.jpg","type":"image\/jpeg"}],"author":"RVM","twitter_card":"summary_large_image","twitter_creator":"@ViajaMenorca","twitter_site":"@ViajaMenorca","twitter_misc":{"Scritto da":"RVM","Tempo di lettura stimato":"6 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.viajamenorca.com\/it\/cosa-fare-a-minorca\/fiere-e-mercati\/mercato-del-pesce\/#article","isPartOf":{"@id":"https:\/\/www.viajamenorca.com\/it\/cosa-fare-a-minorca\/fiere-e-mercati\/mercato-del-pesce\/"},"author":{"name":"RVM","@id":"https:\/\/www.viajamenorca.com\/it\/#\/schema\/person\/a4a17bcf26fbf36b9726dc16edd0a3fc"},"headline":"Mercat del Peix, Mah\u00f3n","datePublished":"2022-03-03T15:10:35+00:00","dateModified":"2026-05-09T22:41:56+00:00","mainEntityOfPage":{"@id":"https:\/\/www.viajamenorca.com\/it\/cosa-fare-a-minorca\/fiere-e-mercati\/mercato-del-pesce\/"},"wordCount":316,"publisher":{"@id":"https:\/\/www.viajamenorca.com\/it\/#organization"},"image":{"@id":"https:\/\/www.viajamenorca.com\/it\/cosa-fare-a-minorca\/fiere-e-mercati\/mercato-del-pesce\/#primaryimage"},"thumbnailUrl":"https:\/\/www.viajamenorca.com\/wp-content\/uploads\/2022\/02\/IMG_20220204_124939_1_stitch-scaled.jpg","keywords":["Cucina di mercato","Mahon","Mercat del peix","Mercato del pesce","Mercato gastronomico","Pescivendolo"],"articleSection":["Ferias y Mercados","Fiere e mercati"],"inLanguage":"it-IT"},{"@type":"WebPage","@id":"https:\/\/www.viajamenorca.com\/it\/cosa-fare-a-minorca\/fiere-e-mercati\/mercato-del-pesce\/","url":"https:\/\/www.viajamenorca.com\/it\/cosa-fare-a-minorca\/fiere-e-mercati\/mercato-del-pesce\/","name":"Mercato del pesce di Mah\u00f3n: tapas, pesce fresco, dove mangiare","isPartOf":{"@id":"https:\/\/www.viajamenorca.com\/it\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.viajamenorca.com\/it\/cosa-fare-a-minorca\/fiere-e-mercati\/mercato-del-pesce\/#primaryimage"},"image":{"@id":"https:\/\/www.viajamenorca.com\/it\/cosa-fare-a-minorca\/fiere-e-mercati\/mercato-del-pesce\/#primaryimage"},"thumbnailUrl":"https:\/\/www.viajamenorca.com\/wp-content\/uploads\/2022\/02\/IMG_20220204_124939_1_stitch-scaled.jpg","datePublished":"2022-03-03T15:10:35+00:00","dateModified":"2026-05-09T22:41:56+00:00","description":"Il mercato del pesce di Mah\u00f3n si trova nel centro della citt\u00e0, molto vicino al mercato di Claustre del Carme, e ospita anche un mercato","breadcrumb":{"@id":"https:\/\/www.viajamenorca.com\/it\/cosa-fare-a-minorca\/fiere-e-mercati\/mercato-del-pesce\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.viajamenorca.com\/it\/cosa-fare-a-minorca\/fiere-e-mercati\/mercato-del-pesce\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.viajamenorca.com\/it\/cosa-fare-a-minorca\/fiere-e-mercati\/mercato-del-pesce\/#primaryimage","url":"https:\/\/www.viajamenorca.com\/wp-content\/uploads\/2022\/02\/IMG_20220204_124939_1_stitch-scaled.jpg","contentUrl":"https:\/\/www.viajamenorca.com\/wp-content\/uploads\/2022\/02\/IMG_20220204_124939_1_stitch-scaled.jpg","width":2560,"height":1124,"caption":"fish market Mah\u00f3n"},{"@type":"BreadcrumbList","@id":"https:\/\/www.viajamenorca.com\/it\/cosa-fare-a-minorca\/fiere-e-mercati\/mercato-del-pesce\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Cosa fare a Minorca","item":"https:\/\/www.viajamenorca.com\/it\/.\/cosa-fare-a-minorca\/"},{"@type":"ListItem","position":2,"name":"Fiere e mercati","item":"https:\/\/www.viajamenorca.com\/it\/.\/cosa-fare-a-minorca\/fiere-e-mercati\/"},{"@type":"ListItem","position":3,"name":"Mercato del pesce"}]},{"@type":"WebSite","@id":"https:\/\/www.viajamenorca.com\/it\/#website","url":"https:\/\/www.viajamenorca.com\/it\/","name":"Viaja a Menorca","description":"La tua avventura a Minorca inizia qui!","publisher":{"@id":"https:\/\/www.viajamenorca.com\/it\/#organization"},"alternateName":"Gu\u00eda tur\u00edstica de Menorca","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.viajamenorca.com\/it\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/www.viajamenorca.com\/it\/#organization","name":"Viaja a Menorca - Gu\u00eda tur\u00edstica","alternateName":"Viaja a Menorca","url":"https:\/\/www.viajamenorca.com\/it\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.viajamenorca.com\/it\/#\/schema\/logo\/image\/","url":"https:\/\/www.viajamenorca.com\/wp-content\/uploads\/2021\/11\/viajamenorca.jpg","contentUrl":"https:\/\/www.viajamenorca.com\/wp-content\/uploads\/2021\/11\/viajamenorca.jpg","width":714,"height":714,"caption":"Viaja a Menorca - Gu\u00eda tur\u00edstica"},"image":{"@id":"https:\/\/www.viajamenorca.com\/it\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/ViajaMenorca\/","https:\/\/x.com\/ViajaMenorca","https:\/\/www.instagram.com\/viaja_menorca\/?hl=es","https:\/\/www.youtube.com\/channel\/UCWtpR3jxp79HeZ8zZfHLhXw"]},{"@type":"Person","@id":"https:\/\/www.viajamenorca.com\/it\/#\/schema\/person\/a4a17bcf26fbf36b9726dc16edd0a3fc","name":"RVM","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.viajamenorca.com\/wp-content\/litespeed\/avatar\/f92762d1538920c5ee7c40d8d2c84bc0.jpg?ver=1778553373","url":"https:\/\/www.viajamenorca.com\/wp-content\/litespeed\/avatar\/f92762d1538920c5ee7c40d8d2c84bc0.jpg?ver=1778553373","contentUrl":"https:\/\/www.viajamenorca.com\/wp-content\/litespeed\/avatar\/f92762d1538920c5ee7c40d8d2c84bc0.jpg?ver=1778553373","caption":"RVM"},"description":"Guia turistica de Menorca creada por un menorquin amante de su tierra, espero que os guste.","sameAs":["http:\/\/www.viajamenorca.com","https:\/\/www.facebook.com\/ViajaMenorca\/","https:\/\/www.instagram.com\/viaja_menorca\/?hl=es","https:\/\/x.com\/ViajaMenorca","https:\/\/www.youtube.com\/c\/ViajamenorcaEs","https:\/\/es.wikipedia.org\/wiki\/Menorca"]}]}},"_links":{"self":[{"href":"https:\/\/www.viajamenorca.com\/it\/wp-json\/wp\/v2\/posts\/70336","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.viajamenorca.com\/it\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.viajamenorca.com\/it\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.viajamenorca.com\/it\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.viajamenorca.com\/it\/wp-json\/wp\/v2\/comments?post=70336"}],"version-history":[{"count":3,"href":"https:\/\/www.viajamenorca.com\/it\/wp-json\/wp\/v2\/posts\/70336\/revisions"}],"predecessor-version":[{"id":71451,"href":"https:\/\/www.viajamenorca.com\/it\/wp-json\/wp\/v2\/posts\/70336\/revisions\/71451"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.viajamenorca.com\/it\/wp-json\/wp\/v2\/media\/20318"}],"wp:attachment":[{"href":"https:\/\/www.viajamenorca.com\/it\/wp-json\/wp\/v2\/media?parent=70336"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.viajamenorca.com\/it\/wp-json\/wp\/v2\/categories?post=70336"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.viajamenorca.com\/it\/wp-json\/wp\/v2\/tags?post=70336"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}